{"id":14634,"date":"2026-04-27T17:04:59","date_gmt":"2026-04-27T20:04:59","guid":{"rendered":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/?p=14634"},"modified":"2026-04-27T17:05:01","modified_gmt":"2026-04-27T20:05:01","slug":"%f0%9f%94%b4estimada-comunidad-educativa","status":"publish","type":"post","link":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/%f0%9f%94%b4estimada-comunidad-educativa\/","title":{"rendered":"&#x1f534;Estimada comunidad educativa:"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><em>\u200bQueremos informarles que el mi\u00e9rcoles pasado el Consejo Escolar de Moreno se comunic\u00f3 con la instituci\u00f3n para informar que esta semana, entre el martes y el mi\u00e9rcoles, se iniciar\u00e1n los arreglos de sanitarios y el recambio de luminarias.<\/em><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><em>\u200bAl respecto, el jueves pasado recibimos la visita de dos inspectores de infraestructura para realizar los relevamientos correspondientes. La empresa designada es Ottal, la cual ya ha efectuado la inspecci\u00f3n t\u00e9cnica y el listado de repuestos necesarios para la obra.<\/em><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><em>\u200bMantendremos a la comunidad informada ante cualquier novedad.<\/em><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><em>\u200bAtentamente,<\/em><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><em>\u200bEquipo Directivo<\/em><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u200bQueremos informarles que el mi\u00e9rcoles pasado el Consejo Escolar de Moreno se comunic\u00f3 con la instituci\u00f3n para informar que esta semana, entre el martes y el mi\u00e9rcoles, se iniciar\u00e1n los arreglos de sanitarios y el recambio de luminarias. \u200bAl respecto, el jueves pasado recibimos la visita de dos inspectores de infraestructura para realizar los relevamientos &#8230; <a title=\"&#x1f534;Estimada comunidad educativa:\" class=\"read-more\" href=\"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/%f0%9f%94%b4estimada-comunidad-educativa\/\" aria-label=\"More on &#x1f534;Estimada comunidad educativa:\">[+]<\/a><\/p>\n","protected":false},"author":9269,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/14634"}],"collection":[{"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/9269"}],"replies":[{"embeddable":true,"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=14634"}],"version-history":[{"count":1,"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/14634\/revisions"}],"predecessor-version":[{"id":14635,"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/14634\/revisions\/14635"}],"wp:attachment":[{"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=14634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=14634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isfd21-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=14634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}